{"id":23292,"date":"2025-10-04T16:48:27","date_gmt":"2025-10-04T14:48:27","guid":{"rendered":"https:\/\/www.soundpr.it\/?post_type=news&#038;p=23292"},"modified":"2025-10-07T16:55:06","modified_gmt":"2025-10-07T14:55:06","slug":"the-north-face-cecilie-bahnsen-continua-la-collab","status":"publish","type":"news","link":"https:\/\/www.soundpr.it\/en\/news\/the-north-face-cecilie-bahnsen-continua-la-collab\/","title":{"rendered":"(Italiano) THE NORTH FACE E CECILIE BAHNSEN PRESENTANO  IL TERZO CAPITOLO DELLA LORO COLLABORAZIONE"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\">Sorry, this entry is only available in <a href=\"https:\/\/www.soundpr.it\/it\/wp-json\/wp\/v2\/news\/23292\" class=\"qtranxs-available-language-link qtranxs-available-language-link-it\" title=\"Italiano\">Italian<\/a>.<\/p>","protected":false},"featured_media":23297,"template":"","news_categories":[143],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title><\/title>\n<meta name=\"description\" content=\"The North Face svela la nuova collaborazione con Cecilie Bahnsen, presentata durante la sfilata Primavera\/Estate 2026 della designer a Parigi.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.soundpr.it\/news\/the-north-face-cecilie-bahnsen-continua-la-collab\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[:it]THE NORTH FACE E CECILIE BAHNSEN PRESENTANO IL TERZO CAPITOLO DELLA LORO COLLABORAZIONE[:] - soundPR\" \/>\n<meta property=\"og:description\" content=\"The North Face svela la nuova collaborazione con Cecilie Bahnsen, presentata durante la sfilata Primavera\/Estate 2026 della designer a Parigi.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.soundpr.it\/news\/the-north-face-cecilie-bahnsen-continua-la-collab\/\" \/>\n<meta property=\"og:site_name\" content=\"soundPR\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-07T14:55:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.soundpr.it\/wp-content\/uploads\/2025\/10\/cec.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"543\" \/>\n\t<meta property=\"og:image:height\" content=\"493\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.soundpr.it\/news\/the-north-face-cecilie-bahnsen-continua-la-collab\/\",\"url\":\"https:\/\/www.soundpr.it\/news\/the-north-face-cecilie-bahnsen-continua-la-collab\/\",\"name\":\"[:it]THE NORTH FACE E CECILIE BAHNSEN PRESENTANO IL TERZO CAPITOLO DELLA LORO COLLABORAZIONE[:] - soundPR\",\"isPartOf\":{\"@id\":\"https:\/\/www.soundpr.it\/#website\"},\"datePublished\":\"2025-10-04T14:48:27+00:00\",\"dateModified\":\"2025-10-07T14:55:06+00:00\",\"description\":\"The North Face svela la nuova collaborazione con Cecilie Bahnsen, presentata durante la sfilata Primavera\/Estate 2026 della designer a Parigi.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.soundpr.it\/news\/the-north-face-cecilie-bahnsen-continua-la-collab\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.soundpr.it\/news\/the-north-face-cecilie-bahnsen-continua-la-collab\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.soundpr.it\/news\/the-north-face-cecilie-bahnsen-continua-la-collab\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.soundpr.it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"THE NORTH FACE E CECILIE BAHNSEN PRESENTANO IL TERZO CAPITOLO DELLA LORO COLLABORAZIONE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.soundpr.it\/#website\",\"url\":\"https:\/\/www.soundpr.it\/\",\"name\":\"soundPR\",\"description\":\"Sound Public Relations\",\"publisher\":{\"@id\":\"https:\/\/www.soundpr.it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.soundpr.it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.soundpr.it\/#organization\",\"name\":\"soundPR\",\"url\":\"https:\/\/www.soundpr.it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.soundpr.it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.soundpr.it\/wp-content\/uploads\/2019\/07\/Logo-hd-wht.png\",\"contentUrl\":\"https:\/\/www.soundpr.it\/wp-content\/uploads\/2019\/07\/Logo-hd-wht.png\",\"width\":168,\"height\":69,\"caption\":\"soundPR\"},\"image\":{\"@id\":\"https:\/\/www.soundpr.it\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[:it]THE NORTH FACE E CECILIE BAHNSEN PRESENTANO IL TERZO CAPITOLO DELLA LORO COLLABORAZIONE[:] - soundPR","description":"The North Face svela la nuova collaborazione con Cecilie Bahnsen, presentata durante la sfilata Primavera\/Estate 2026 della designer a Parigi.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.soundpr.it\/news\/the-north-face-cecilie-bahnsen-continua-la-collab\/","og_locale":"en_US","og_type":"article","og_title":"[:it]THE NORTH FACE E CECILIE BAHNSEN PRESENTANO IL TERZO CAPITOLO DELLA LORO COLLABORAZIONE[:] - soundPR","og_description":"The North Face svela la nuova collaborazione con Cecilie Bahnsen, presentata durante la sfilata Primavera\/Estate 2026 della designer a Parigi.","og_url":"https:\/\/www.soundpr.it\/news\/the-north-face-cecilie-bahnsen-continua-la-collab\/","og_site_name":"soundPR","article_modified_time":"2025-10-07T14:55:06+00:00","og_image":[{"width":543,"height":493,"url":"https:\/\/www.soundpr.it\/wp-content\/uploads\/2025\/10\/cec.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.soundpr.it\/news\/the-north-face-cecilie-bahnsen-continua-la-collab\/","url":"https:\/\/www.soundpr.it\/news\/the-north-face-cecilie-bahnsen-continua-la-collab\/","name":"[:it]THE NORTH FACE E CECILIE BAHNSEN PRESENTANO IL TERZO CAPITOLO DELLA LORO COLLABORAZIONE[:] - soundPR","isPartOf":{"@id":"https:\/\/www.soundpr.it\/#website"},"datePublished":"2025-10-04T14:48:27+00:00","dateModified":"2025-10-07T14:55:06+00:00","description":"The North Face svela la nuova collaborazione con Cecilie Bahnsen, presentata durante la sfilata Primavera\/Estate 2026 della designer a Parigi.","breadcrumb":{"@id":"https:\/\/www.soundpr.it\/news\/the-north-face-cecilie-bahnsen-continua-la-collab\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.soundpr.it\/news\/the-north-face-cecilie-bahnsen-continua-la-collab\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.soundpr.it\/news\/the-north-face-cecilie-bahnsen-continua-la-collab\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.soundpr.it\/"},{"@type":"ListItem","position":2,"name":"THE NORTH FACE E CECILIE BAHNSEN PRESENTANO IL TERZO CAPITOLO DELLA LORO COLLABORAZIONE"}]},{"@type":"WebSite","@id":"https:\/\/www.soundpr.it\/#website","url":"https:\/\/www.soundpr.it\/","name":"soundPR","description":"Sound Public Relations","publisher":{"@id":"https:\/\/www.soundpr.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.soundpr.it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.soundpr.it\/#organization","name":"soundPR","url":"https:\/\/www.soundpr.it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.soundpr.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.soundpr.it\/wp-content\/uploads\/2019\/07\/Logo-hd-wht.png","contentUrl":"https:\/\/www.soundpr.it\/wp-content\/uploads\/2019\/07\/Logo-hd-wht.png","width":168,"height":69,"caption":"soundPR"},"image":{"@id":"https:\/\/www.soundpr.it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.soundpr.it\/en\/wp-json\/wp\/v2\/news\/23292"}],"collection":[{"href":"https:\/\/www.soundpr.it\/en\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/www.soundpr.it\/en\/wp-json\/wp\/v2\/types\/news"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.soundpr.it\/en\/wp-json\/wp\/v2\/media\/23297"}],"wp:attachment":[{"href":"https:\/\/www.soundpr.it\/en\/wp-json\/wp\/v2\/media?parent=23292"}],"wp:term":[{"taxonomy":"news_categories","embeddable":true,"href":"https:\/\/www.soundpr.it\/en\/wp-json\/wp\/v2\/news_categories?post=23292"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}