{"id":23017,"date":"2025-03-14T10:15:18","date_gmt":"2025-03-14T09:15:18","guid":{"rendered":"https:\/\/www.soundpr.it\/?post_type=news&#038;p=23017"},"modified":"2025-03-14T11:31:09","modified_gmt":"2025-03-14T10:31:09","slug":"nuova-collaborazione-the-north-face-cecile-bahnsen","status":"publish","type":"news","link":"https:\/\/www.soundpr.it\/en\/news\/nuova-collaborazione-the-north-face-cecile-bahnsen\/","title":{"rendered":"(Italiano) LA COLLEZIONE FRUTTO DELLA COLLABORAZIONE TRA THE NORTH FACE E CECILIE BAHNSEN ADESSO LIVE"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\">Sorry, this entry is only available in <a href=\"https:\/\/www.soundpr.it\/it\/wp-json\/wp\/v2\/news\/23017\" class=\"qtranxs-available-language-link qtranxs-available-language-link-it\" title=\"Italiano\">Italian<\/a>.<\/p>","protected":false},"featured_media":23029,"template":"","news_categories":[143],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Scopri la collaborazione tra The North Face e Cecile Bahnsen<\/title>\n<meta name=\"description\" content=\"Scopri la nuova collaborazione tra the North Face e Cecile Bahnsen\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.soundpr.it\/news\/nuova-collaborazione-the-north-face-cecile-bahnsen\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Scopri la collaborazione tra The North Face e Cecile Bahnsen\" \/>\n<meta property=\"og:description\" content=\"Scopri la nuova collaborazione tra the North Face e Cecile Bahnsen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.soundpr.it\/news\/nuova-collaborazione-the-north-face-cecile-bahnsen\/\" \/>\n<meta property=\"og:site_name\" content=\"soundPR\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-14T10:31:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.soundpr.it\/wp-content\/uploads\/2025\/03\/per-blog.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1217\" \/>\n\t<meta property=\"og:image:height\" content=\"747\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.soundpr.it\/news\/nuova-collaborazione-the-north-face-cecile-bahnsen\/\",\"url\":\"https:\/\/www.soundpr.it\/news\/nuova-collaborazione-the-north-face-cecile-bahnsen\/\",\"name\":\"Scopri la collaborazione tra The North Face e Cecile Bahnsen\",\"isPartOf\":{\"@id\":\"https:\/\/www.soundpr.it\/#website\"},\"datePublished\":\"2025-03-14T09:15:18+00:00\",\"dateModified\":\"2025-03-14T10:31:09+00:00\",\"description\":\"Scopri la nuova collaborazione tra the North Face e Cecile Bahnsen\",\"breadcrumb\":{\"@id\":\"https:\/\/www.soundpr.it\/news\/nuova-collaborazione-the-north-face-cecile-bahnsen\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.soundpr.it\/news\/nuova-collaborazione-the-north-face-cecile-bahnsen\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.soundpr.it\/news\/nuova-collaborazione-the-north-face-cecile-bahnsen\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.soundpr.it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LA COLLEZIONE FRUTTO DELLA COLLABORAZIONE TRA THE NORTH FACE E CECILIE BAHNSEN ADESSO LIVE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.soundpr.it\/#website\",\"url\":\"https:\/\/www.soundpr.it\/\",\"name\":\"soundPR\",\"description\":\"Sound Public Relations\",\"publisher\":{\"@id\":\"https:\/\/www.soundpr.it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.soundpr.it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.soundpr.it\/#organization\",\"name\":\"soundPR\",\"url\":\"https:\/\/www.soundpr.it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.soundpr.it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.soundpr.it\/wp-content\/uploads\/2019\/07\/Logo-hd-wht.png\",\"contentUrl\":\"https:\/\/www.soundpr.it\/wp-content\/uploads\/2019\/07\/Logo-hd-wht.png\",\"width\":168,\"height\":69,\"caption\":\"soundPR\"},\"image\":{\"@id\":\"https:\/\/www.soundpr.it\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Scopri la collaborazione tra The North Face e Cecile Bahnsen","description":"Scopri la nuova collaborazione tra the North Face e Cecile Bahnsen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.soundpr.it\/news\/nuova-collaborazione-the-north-face-cecile-bahnsen\/","og_locale":"en_US","og_type":"article","og_title":"Scopri la collaborazione tra The North Face e Cecile Bahnsen","og_description":"Scopri la nuova collaborazione tra the North Face e Cecile Bahnsen","og_url":"https:\/\/www.soundpr.it\/news\/nuova-collaborazione-the-north-face-cecile-bahnsen\/","og_site_name":"soundPR","article_modified_time":"2025-03-14T10:31:09+00:00","og_image":[{"width":1217,"height":747,"url":"https:\/\/www.soundpr.it\/wp-content\/uploads\/2025\/03\/per-blog.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.soundpr.it\/news\/nuova-collaborazione-the-north-face-cecile-bahnsen\/","url":"https:\/\/www.soundpr.it\/news\/nuova-collaborazione-the-north-face-cecile-bahnsen\/","name":"Scopri la collaborazione tra The North Face e Cecile Bahnsen","isPartOf":{"@id":"https:\/\/www.soundpr.it\/#website"},"datePublished":"2025-03-14T09:15:18+00:00","dateModified":"2025-03-14T10:31:09+00:00","description":"Scopri la nuova collaborazione tra the North Face e Cecile Bahnsen","breadcrumb":{"@id":"https:\/\/www.soundpr.it\/news\/nuova-collaborazione-the-north-face-cecile-bahnsen\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.soundpr.it\/news\/nuova-collaborazione-the-north-face-cecile-bahnsen\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.soundpr.it\/news\/nuova-collaborazione-the-north-face-cecile-bahnsen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.soundpr.it\/"},{"@type":"ListItem","position":2,"name":"LA COLLEZIONE FRUTTO DELLA COLLABORAZIONE TRA THE NORTH FACE E CECILIE BAHNSEN ADESSO LIVE"}]},{"@type":"WebSite","@id":"https:\/\/www.soundpr.it\/#website","url":"https:\/\/www.soundpr.it\/","name":"soundPR","description":"Sound Public Relations","publisher":{"@id":"https:\/\/www.soundpr.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.soundpr.it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.soundpr.it\/#organization","name":"soundPR","url":"https:\/\/www.soundpr.it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.soundpr.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.soundpr.it\/wp-content\/uploads\/2019\/07\/Logo-hd-wht.png","contentUrl":"https:\/\/www.soundpr.it\/wp-content\/uploads\/2019\/07\/Logo-hd-wht.png","width":168,"height":69,"caption":"soundPR"},"image":{"@id":"https:\/\/www.soundpr.it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.soundpr.it\/en\/wp-json\/wp\/v2\/news\/23017"}],"collection":[{"href":"https:\/\/www.soundpr.it\/en\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/www.soundpr.it\/en\/wp-json\/wp\/v2\/types\/news"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.soundpr.it\/en\/wp-json\/wp\/v2\/media\/23029"}],"wp:attachment":[{"href":"https:\/\/www.soundpr.it\/en\/wp-json\/wp\/v2\/media?parent=23017"}],"wp:term":[{"taxonomy":"news_categories","embeddable":true,"href":"https:\/\/www.soundpr.it\/en\/wp-json\/wp\/v2\/news_categories?post=23017"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}