{"id":20259,"date":"2021-04-21T15:58:52","date_gmt":"2021-04-21T13:58:52","guid":{"rendered":"https:\/\/www.soundpr.it\/?post_type=news&#038;p=20259"},"modified":"2021-04-21T15:58:52","modified_gmt":"2021-04-21T13:58:52","slug":"sempre-piu-cybercriminali-sfruttano-tls-nascondere-malware-sophos-risponde-nuova-serie-firewall-xgs-garantisce-migliore-ispezione-tls","status":"publish","type":"news","link":"https:\/\/www.soundpr.it\/en\/news\/sempre-piu-cybercriminali-sfruttano-tls-nascondere-malware-sophos-risponde-nuova-serie-firewall-xgs-garantisce-migliore-ispezione-tls\/","title":{"rendered":"(Italiano) Sempre pi\u00f9 cybercriminali sfruttano i TLS per nascondere il malware:  Sophos risponde con la nuova serie di firewall XGS, che garantisce la migliore ispezione TLS"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\">Sorry, this entry is only available in <a href=\"https:\/\/www.soundpr.it\/it\/wp-json\/wp\/v2\/news\/20259\" class=\"qtranxs-available-language-link qtranxs-available-language-link-it\" title=\"Italiano\">Italian<\/a>.<\/p>","protected":false},"featured_media":20262,"template":"","news_categories":[147],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title><\/title>\n<meta name=\"description\" content=\"Le nuove appliance vengono presentate contestualmente ai risultati della ricerca che evidenzia un sensibile aumento dei cyberattacchi che sfruttano proprio i TLS\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.soundpr.it\/news\/sempre-piu-cybercriminali-sfruttano-tls-nascondere-malware-sophos-risponde-nuova-serie-firewall-xgs-garantisce-migliore-ispezione-tls\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[:it]Sempre pi\u00f9 cybercriminali sfruttano i TLS per nascondere il malware: Sophos risponde con la nuova serie di firewall XGS, che garantisce la migliore ispezione TLS[:] - soundPR\" \/>\n<meta property=\"og:description\" content=\"Le nuove appliance vengono presentate contestualmente ai risultati della ricerca che evidenzia un sensibile aumento dei cyberattacchi che sfruttano proprio i TLS\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.soundpr.it\/news\/sempre-piu-cybercriminali-sfruttano-tls-nascondere-malware-sophos-risponde-nuova-serie-firewall-xgs-garantisce-migliore-ispezione-tls\/\" \/>\n<meta property=\"og:site_name\" content=\"soundPR\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.soundpr.it\/wp-content\/uploads\/2021\/04\/Sophos-Firewall-Control-Center-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1860\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.soundpr.it\/news\/sempre-piu-cybercriminali-sfruttano-tls-nascondere-malware-sophos-risponde-nuova-serie-firewall-xgs-garantisce-migliore-ispezione-tls\/\",\"url\":\"https:\/\/www.soundpr.it\/news\/sempre-piu-cybercriminali-sfruttano-tls-nascondere-malware-sophos-risponde-nuova-serie-firewall-xgs-garantisce-migliore-ispezione-tls\/\",\"name\":\"[:it]Sempre pi\u00f9 cybercriminali sfruttano i TLS per nascondere il malware: Sophos risponde con la nuova serie di firewall XGS, che garantisce la migliore ispezione TLS[:] - soundPR\",\"isPartOf\":{\"@id\":\"https:\/\/www.soundpr.it\/#website\"},\"datePublished\":\"2021-04-21T13:58:52+00:00\",\"dateModified\":\"2021-04-21T13:58:52+00:00\",\"description\":\"Le nuove appliance vengono presentate contestualmente ai risultati della ricerca che evidenzia un sensibile aumento dei cyberattacchi che sfruttano proprio i TLS\",\"breadcrumb\":{\"@id\":\"https:\/\/www.soundpr.it\/news\/sempre-piu-cybercriminali-sfruttano-tls-nascondere-malware-sophos-risponde-nuova-serie-firewall-xgs-garantisce-migliore-ispezione-tls\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.soundpr.it\/news\/sempre-piu-cybercriminali-sfruttano-tls-nascondere-malware-sophos-risponde-nuova-serie-firewall-xgs-garantisce-migliore-ispezione-tls\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.soundpr.it\/news\/sempre-piu-cybercriminali-sfruttano-tls-nascondere-malware-sophos-risponde-nuova-serie-firewall-xgs-garantisce-migliore-ispezione-tls\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.soundpr.it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sempre pi\u00f9 cybercriminali sfruttano i TLS per nascondere il malware: Sophos risponde con la nuova serie di firewall XGS, che garantisce la migliore ispezione TLS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.soundpr.it\/#website\",\"url\":\"https:\/\/www.soundpr.it\/\",\"name\":\"soundPR\",\"description\":\"Sound Public Relations\",\"publisher\":{\"@id\":\"https:\/\/www.soundpr.it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.soundpr.it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.soundpr.it\/#organization\",\"name\":\"soundPR\",\"url\":\"https:\/\/www.soundpr.it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.soundpr.it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.soundpr.it\/wp-content\/uploads\/2019\/07\/Logo-hd-wht.png\",\"contentUrl\":\"https:\/\/www.soundpr.it\/wp-content\/uploads\/2019\/07\/Logo-hd-wht.png\",\"width\":168,\"height\":69,\"caption\":\"soundPR\"},\"image\":{\"@id\":\"https:\/\/www.soundpr.it\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[:it]Sempre pi\u00f9 cybercriminali sfruttano i TLS per nascondere il malware: Sophos risponde con la nuova serie di firewall XGS, che garantisce la migliore ispezione TLS[:] - soundPR","description":"Le nuove appliance vengono presentate contestualmente ai risultati della ricerca che evidenzia un sensibile aumento dei cyberattacchi che sfruttano proprio i TLS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.soundpr.it\/news\/sempre-piu-cybercriminali-sfruttano-tls-nascondere-malware-sophos-risponde-nuova-serie-firewall-xgs-garantisce-migliore-ispezione-tls\/","og_locale":"en_US","og_type":"article","og_title":"[:it]Sempre pi\u00f9 cybercriminali sfruttano i TLS per nascondere il malware: Sophos risponde con la nuova serie di firewall XGS, che garantisce la migliore ispezione TLS[:] - soundPR","og_description":"Le nuove appliance vengono presentate contestualmente ai risultati della ricerca che evidenzia un sensibile aumento dei cyberattacchi che sfruttano proprio i TLS","og_url":"https:\/\/www.soundpr.it\/news\/sempre-piu-cybercriminali-sfruttano-tls-nascondere-malware-sophos-risponde-nuova-serie-firewall-xgs-garantisce-migliore-ispezione-tls\/","og_site_name":"soundPR","og_image":[{"width":2560,"height":1860,"url":"https:\/\/www.soundpr.it\/wp-content\/uploads\/2021\/04\/Sophos-Firewall-Control-Center-1-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.soundpr.it\/news\/sempre-piu-cybercriminali-sfruttano-tls-nascondere-malware-sophos-risponde-nuova-serie-firewall-xgs-garantisce-migliore-ispezione-tls\/","url":"https:\/\/www.soundpr.it\/news\/sempre-piu-cybercriminali-sfruttano-tls-nascondere-malware-sophos-risponde-nuova-serie-firewall-xgs-garantisce-migliore-ispezione-tls\/","name":"[:it]Sempre pi\u00f9 cybercriminali sfruttano i TLS per nascondere il malware: Sophos risponde con la nuova serie di firewall XGS, che garantisce la migliore ispezione TLS[:] - soundPR","isPartOf":{"@id":"https:\/\/www.soundpr.it\/#website"},"datePublished":"2021-04-21T13:58:52+00:00","dateModified":"2021-04-21T13:58:52+00:00","description":"Le nuove appliance vengono presentate contestualmente ai risultati della ricerca che evidenzia un sensibile aumento dei cyberattacchi che sfruttano proprio i TLS","breadcrumb":{"@id":"https:\/\/www.soundpr.it\/news\/sempre-piu-cybercriminali-sfruttano-tls-nascondere-malware-sophos-risponde-nuova-serie-firewall-xgs-garantisce-migliore-ispezione-tls\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.soundpr.it\/news\/sempre-piu-cybercriminali-sfruttano-tls-nascondere-malware-sophos-risponde-nuova-serie-firewall-xgs-garantisce-migliore-ispezione-tls\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.soundpr.it\/news\/sempre-piu-cybercriminali-sfruttano-tls-nascondere-malware-sophos-risponde-nuova-serie-firewall-xgs-garantisce-migliore-ispezione-tls\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.soundpr.it\/"},{"@type":"ListItem","position":2,"name":"Sempre pi\u00f9 cybercriminali sfruttano i TLS per nascondere il malware: Sophos risponde con la nuova serie di firewall XGS, che garantisce la migliore ispezione TLS"}]},{"@type":"WebSite","@id":"https:\/\/www.soundpr.it\/#website","url":"https:\/\/www.soundpr.it\/","name":"soundPR","description":"Sound Public Relations","publisher":{"@id":"https:\/\/www.soundpr.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.soundpr.it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.soundpr.it\/#organization","name":"soundPR","url":"https:\/\/www.soundpr.it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.soundpr.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.soundpr.it\/wp-content\/uploads\/2019\/07\/Logo-hd-wht.png","contentUrl":"https:\/\/www.soundpr.it\/wp-content\/uploads\/2019\/07\/Logo-hd-wht.png","width":168,"height":69,"caption":"soundPR"},"image":{"@id":"https:\/\/www.soundpr.it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.soundpr.it\/en\/wp-json\/wp\/v2\/news\/20259"}],"collection":[{"href":"https:\/\/www.soundpr.it\/en\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/www.soundpr.it\/en\/wp-json\/wp\/v2\/types\/news"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.soundpr.it\/en\/wp-json\/wp\/v2\/media\/20262"}],"wp:attachment":[{"href":"https:\/\/www.soundpr.it\/en\/wp-json\/wp\/v2\/media?parent=20259"}],"wp:term":[{"taxonomy":"news_categories","embeddable":true,"href":"https:\/\/www.soundpr.it\/en\/wp-json\/wp\/v2\/news_categories?post=20259"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}