{"id":19742,"date":"2020-10-29T09:12:19","date_gmt":"2020-10-29T08:12:19","guid":{"rendered":"https:\/\/www.soundpr.it\/?post_type=news&#038;p=19742"},"modified":"2020-10-29T08:57:35","modified_gmt":"2020-10-29T07:57:35","slug":"sophos-rapid-response-cybersecurity","status":"publish","type":"news","link":"https:\/\/www.soundpr.it\/en\/news\/sophos-rapid-response-cybersecurity\/","title":{"rendered":"(Italiano) Sophos Rapid Response: il nuovo servizio di cybersecurity  che identifica e neutralizza gli attacchi informatici riducendo al minimo i danni e i tempi di ripristino"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\">Sorry, this entry is only available in <a href=\"https:\/\/www.soundpr.it\/it\/wp-json\/wp\/v2\/news\/19742\" class=\"qtranxs-available-language-link qtranxs-available-language-link-it\" title=\"Italiano\">Italian<\/a>.<\/p>","protected":false},"featured_media":15630,"template":"","news_categories":[147],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title><\/title>\n<meta name=\"description\" content=\"Sophos ha reso disponibile Sophos Rapid Response, il primo servizio di remote incident response a costo fisso\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.soundpr.it\/news\/sophos-rapid-response-cybersecurity\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[:it]Sophos Rapid Response: il nuovo servizio di cybersecurity che identifica e neutralizza gli attacchi informatici riducendo al minimo i danni e i tempi di ripristino[:] - soundPR\" \/>\n<meta property=\"og:description\" content=\"Sophos ha reso disponibile Sophos Rapid Response, il primo servizio di remote incident response a costo fisso\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.soundpr.it\/news\/sophos-rapid-response-cybersecurity\/\" \/>\n<meta property=\"og:site_name\" content=\"soundPR\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-29T07:57:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.soundpr.it\/wp-content\/uploads\/2019\/07\/sophos_log.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"624\" \/>\n\t<meta property=\"og:image:height\" content=\"295\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.soundpr.it\/news\/sophos-rapid-response-cybersecurity\/\",\"url\":\"https:\/\/www.soundpr.it\/news\/sophos-rapid-response-cybersecurity\/\",\"name\":\"[:it]Sophos Rapid Response: il nuovo servizio di cybersecurity che identifica e neutralizza gli attacchi informatici riducendo al minimo i danni e i tempi di ripristino[:] - soundPR\",\"isPartOf\":{\"@id\":\"https:\/\/www.soundpr.it\/#website\"},\"datePublished\":\"2020-10-29T08:12:19+00:00\",\"dateModified\":\"2020-10-29T07:57:35+00:00\",\"description\":\"Sophos ha reso disponibile Sophos Rapid Response, il primo servizio di remote incident response a costo fisso\",\"breadcrumb\":{\"@id\":\"https:\/\/www.soundpr.it\/news\/sophos-rapid-response-cybersecurity\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.soundpr.it\/news\/sophos-rapid-response-cybersecurity\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.soundpr.it\/news\/sophos-rapid-response-cybersecurity\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.soundpr.it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sophos Rapid Response: il nuovo servizio di cybersecurity che identifica e neutralizza gli attacchi informatici riducendo al minimo i danni e i tempi di ripristino\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.soundpr.it\/#website\",\"url\":\"https:\/\/www.soundpr.it\/\",\"name\":\"soundPR\",\"description\":\"Sound Public Relations\",\"publisher\":{\"@id\":\"https:\/\/www.soundpr.it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.soundpr.it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.soundpr.it\/#organization\",\"name\":\"soundPR\",\"url\":\"https:\/\/www.soundpr.it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.soundpr.it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.soundpr.it\/wp-content\/uploads\/2019\/07\/Logo-hd-wht.png\",\"contentUrl\":\"https:\/\/www.soundpr.it\/wp-content\/uploads\/2019\/07\/Logo-hd-wht.png\",\"width\":168,\"height\":69,\"caption\":\"soundPR\"},\"image\":{\"@id\":\"https:\/\/www.soundpr.it\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[:it]Sophos Rapid Response: il nuovo servizio di cybersecurity che identifica e neutralizza gli attacchi informatici riducendo al minimo i danni e i tempi di ripristino[:] - soundPR","description":"Sophos ha reso disponibile Sophos Rapid Response, il primo servizio di remote incident response a costo fisso","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.soundpr.it\/news\/sophos-rapid-response-cybersecurity\/","og_locale":"en_US","og_type":"article","og_title":"[:it]Sophos Rapid Response: il nuovo servizio di cybersecurity che identifica e neutralizza gli attacchi informatici riducendo al minimo i danni e i tempi di ripristino[:] - soundPR","og_description":"Sophos ha reso disponibile Sophos Rapid Response, il primo servizio di remote incident response a costo fisso","og_url":"https:\/\/www.soundpr.it\/news\/sophos-rapid-response-cybersecurity\/","og_site_name":"soundPR","article_modified_time":"2020-10-29T07:57:35+00:00","og_image":[{"width":624,"height":295,"url":"https:\/\/www.soundpr.it\/wp-content\/uploads\/2019\/07\/sophos_log.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.soundpr.it\/news\/sophos-rapid-response-cybersecurity\/","url":"https:\/\/www.soundpr.it\/news\/sophos-rapid-response-cybersecurity\/","name":"[:it]Sophos Rapid Response: il nuovo servizio di cybersecurity che identifica e neutralizza gli attacchi informatici riducendo al minimo i danni e i tempi di ripristino[:] - soundPR","isPartOf":{"@id":"https:\/\/www.soundpr.it\/#website"},"datePublished":"2020-10-29T08:12:19+00:00","dateModified":"2020-10-29T07:57:35+00:00","description":"Sophos ha reso disponibile Sophos Rapid Response, il primo servizio di remote incident response a costo fisso","breadcrumb":{"@id":"https:\/\/www.soundpr.it\/news\/sophos-rapid-response-cybersecurity\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.soundpr.it\/news\/sophos-rapid-response-cybersecurity\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.soundpr.it\/news\/sophos-rapid-response-cybersecurity\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.soundpr.it\/"},{"@type":"ListItem","position":2,"name":"Sophos Rapid Response: il nuovo servizio di cybersecurity che identifica e neutralizza gli attacchi informatici riducendo al minimo i danni e i tempi di ripristino"}]},{"@type":"WebSite","@id":"https:\/\/www.soundpr.it\/#website","url":"https:\/\/www.soundpr.it\/","name":"soundPR","description":"Sound Public Relations","publisher":{"@id":"https:\/\/www.soundpr.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.soundpr.it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.soundpr.it\/#organization","name":"soundPR","url":"https:\/\/www.soundpr.it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.soundpr.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.soundpr.it\/wp-content\/uploads\/2019\/07\/Logo-hd-wht.png","contentUrl":"https:\/\/www.soundpr.it\/wp-content\/uploads\/2019\/07\/Logo-hd-wht.png","width":168,"height":69,"caption":"soundPR"},"image":{"@id":"https:\/\/www.soundpr.it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.soundpr.it\/en\/wp-json\/wp\/v2\/news\/19742"}],"collection":[{"href":"https:\/\/www.soundpr.it\/en\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/www.soundpr.it\/en\/wp-json\/wp\/v2\/types\/news"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.soundpr.it\/en\/wp-json\/wp\/v2\/media\/15630"}],"wp:attachment":[{"href":"https:\/\/www.soundpr.it\/en\/wp-json\/wp\/v2\/media?parent=19742"}],"wp:term":[{"taxonomy":"news_categories","embeddable":true,"href":"https:\/\/www.soundpr.it\/en\/wp-json\/wp\/v2\/news_categories?post=19742"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}