{"id":17405,"date":"2019-07-04T00:00:00","date_gmt":"2019-07-03T22:00:00","guid":{"rendered":"https:\/\/www.soundpr.it\/post_news\/the-north-face-conferma-il-suo-impegno-nella-tutela-dellambiente-e-della-natura-portando-la-sua-community-in-valle-daosta-per-un-mountain-educational-trekking\/"},"modified":"2019-07-04T00:00:00","modified_gmt":"2019-07-03T22:00:00","slug":"the-north-face-conferma-il-suo-impegno-nella-tutela-dellambiente-e-della-natura-portando-la-sua-community-in-valle-daosta-per-un-mountain-educational-trekking","status":"publish","type":"news","link":"https:\/\/www.soundpr.it\/en\/news\/the-north-face-conferma-il-suo-impegno-nella-tutela-dellambiente-e-della-natura-portando-la-sua-community-in-valle-daosta-per-un-mountain-educational-trekking\/","title":{"rendered":"The North Face conferma il suo impegno nella tutela dell\u2019ambiente e della natura  portando la sua Community in Valle d\u2019Aosta per un MOUNTAIN EDUCATIONAL TREKKING"},"content":{"rendered":"<p style=\"text-align: justify;\"><em>Appuntamento il 13 luglio a Gressoney-Saint-Jean<\/em><\/p>\n<p>Il prossimo appuntamento fuori citt\u00e0 organizzato da The North Face per la Community Never Stop Milano sar\u00e0 sui monti della Valle d\u2019Aosta, a Gressoney-Saint-Jean. Un\u2019occasione per scoprire posti incantevoli immersi della natura e contribuire attivamente a ripulire i sentieri dai rifiuti, riportando cos\u00ec l\u2019ambiente al suo stato naturale.<\/p>\n<p style=\"text-align: justify;\"><strong>Sabato 13 luglio 2019<\/strong> la Community partir\u00e0 da Milano per<strong> Gressoney-Saint-Jean<\/strong>, dove prender\u00e0 parte al <strong>Mountain Educational Trekking, <\/strong>accompagnata da uno storytelling speciale da parte del Corpo Forestale della Valle d\u2019Aosta che illustrer\u00e0 ai partecipanti le bellezze della flora e della fauna del territorio.<\/p>\n<p style=\"text-align: justify;\">L\u2019iniziativa \u00e8 dedicata principalmente a <strong>trekker con esperienza. <\/strong><\/p>\n<p style=\"text-align: justify;\">Un\u2019occasione per imparare a conoscere meglio un territorio molto apprezzato dagli appassionati di montagna, e al contempo di contribuire concretamente a tutelare l\u2019ambiente che ci circonda; questo appuntamento rispecchia perfettamente lo spirito della campagna \u201cExplore Mode\u201d, lanciata ad aprile dal marchio con l\u2019obiettivo di\u00a0 incentivare le persone a staccare dalla loro vita digitale e creare nuove connessioni con l\u2019ambiente circostante, con gli altri e con s\u00e9 stessi, in uno sforzo congiunto che punti a migliorare il mondo.<\/p>\n<p style=\"text-align: justify;\">Tutti i partecipanti\u00a0 all\u2019arrivo dovranno essere muniti di scarpe da trekking o trail, un cambio asciutto e riserve alimentari e idriche per tutto il giorno.<\/p>\n<p style=\"text-align: justify;\">Il programma dalla giornata \u00e8 il seguente:<\/p>\n<ul>\n<li>00 partenza da Milano \u2013 MM1 Pagano con bus<\/li>\n<li>00 arrivo a Gressoney-Saint-Jean<\/li>\n<li>15-10.00 incontro e briefing con i rappresentanti del Corpo Forestale della valle: \u201cLa Montagna: un\u2019ecosistema delicato e prezioso e il ruolo fondamentale della Guardia Forestale\u201d<\/li>\n<li>15 si parte con il \u2018Mountain Educational Trekking\u2019 in compagnia dei forestali esperti per un percorso di circa 10km con 1200 D+, alla scoperta dei fascinosi territori di Gressoney Weissmatten \u2013 Punta della Regina \u2013 Col Ranzola \u2013 Gressoney.<\/li>\n<li>Rientro previsto per le 19.00 massimo a Milano.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Come di consueto<strong> l\u2019evento \u00e8 gratuito<\/strong>, e con <strong>disponibilit\u00e0 di posti limitata<\/strong>.<\/p>\n<p style=\"text-align: justify;\"><strong>E\u2019 necessario iscriversi al link:<\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.eventbrite.co.uk\/e\/neverstopmilano-mountain-educational-trekking-tickets-64659830293\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.eventbrite.co.uk\/e\/neverstopmilano-mountain-educational-trekking-tickets-64659830293<\/a><\/p>\n<p style=\"text-align: justify;\">Per restare aggiornati sugli eventi della Community: <strong><a href=\"https:\/\/www.facebook.com\/NeverStopMilano\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.facebook.com\/NeverStopMilano\/<\/a><\/strong><\/p>\n<p style=\"text-align: justify;\"><em>Per condividere l\u2019esperienza sui social: #neverstopmilano #Itrainfree<\/em><\/p>\n","protected":false},"featured_media":17406,"template":"","news_categories":[143],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>The North Face conferma il suo impegno nella tutela dell\u2019ambiente e della natura portando la sua Community in Valle d\u2019Aosta per un MOUNTAIN EDUCATIONAL TREKKING - soundPR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.soundpr.it\/news\/the-north-face-conferma-il-suo-impegno-nella-tutela-dellambiente-e-della-natura-portando-la-sua-community-in-valle-daosta-per-un-mountain-educational-trekking\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The North Face conferma il suo impegno nella tutela dell\u2019ambiente e della natura portando la sua Community in Valle d\u2019Aosta per un MOUNTAIN EDUCATIONAL TREKKING - soundPR\" \/>\n<meta property=\"og:description\" content=\"Appuntamento il 13 luglio a Gressoney-Saint-Jean Il prossimo appuntamento fuori citt\u00e0 organizzato da The North Face per la Community Never Stop Milano sar\u00e0 sui monti della Valle d\u2019Aosta, a Gressoney-Saint-Jean. Un\u2019occasione per scoprire posti incantevoli immersi della natura e contribuire attivamente a ripulire i sentieri dai rifiuti, riportando cos\u00ec l\u2019ambiente al suo stato naturale. Sabato [...]Read More...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.soundpr.it\/news\/the-north-face-conferma-il-suo-impegno-nella-tutela-dellambiente-e-della-natura-portando-la-sua-community-in-valle-daosta-per-un-mountain-educational-trekking\/\" \/>\n<meta property=\"og:site_name\" content=\"soundPR\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.soundpr.it\/wp-content\/uploads\/2019\/07\/TNF_MOUNTAIN-EDUCATIONAL-TREKKING.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"721\" \/>\n\t<meta property=\"og:image:height\" content=\"345\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.soundpr.it\/news\/the-north-face-conferma-il-suo-impegno-nella-tutela-dellambiente-e-della-natura-portando-la-sua-community-in-valle-daosta-per-un-mountain-educational-trekking\/\",\"url\":\"https:\/\/www.soundpr.it\/news\/the-north-face-conferma-il-suo-impegno-nella-tutela-dellambiente-e-della-natura-portando-la-sua-community-in-valle-daosta-per-un-mountain-educational-trekking\/\",\"name\":\"The North Face conferma il suo impegno nella tutela dell\u2019ambiente e della natura portando la sua Community in Valle d\u2019Aosta per un MOUNTAIN EDUCATIONAL TREKKING - soundPR\",\"isPartOf\":{\"@id\":\"https:\/\/www.soundpr.it\/#website\"},\"datePublished\":\"2019-07-03T22:00:00+00:00\",\"dateModified\":\"2019-07-03T22:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.soundpr.it\/news\/the-north-face-conferma-il-suo-impegno-nella-tutela-dellambiente-e-della-natura-portando-la-sua-community-in-valle-daosta-per-un-mountain-educational-trekking\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.soundpr.it\/news\/the-north-face-conferma-il-suo-impegno-nella-tutela-dellambiente-e-della-natura-portando-la-sua-community-in-valle-daosta-per-un-mountain-educational-trekking\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.soundpr.it\/news\/the-north-face-conferma-il-suo-impegno-nella-tutela-dellambiente-e-della-natura-portando-la-sua-community-in-valle-daosta-per-un-mountain-educational-trekking\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.soundpr.it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"The North Face conferma il suo impegno nella tutela dell\u2019ambiente e della natura portando la sua Community in Valle d\u2019Aosta per un MOUNTAIN EDUCATIONAL TREKKING\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.soundpr.it\/#website\",\"url\":\"https:\/\/www.soundpr.it\/\",\"name\":\"soundPR\",\"description\":\"Sound Public Relations\",\"publisher\":{\"@id\":\"https:\/\/www.soundpr.it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.soundpr.it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.soundpr.it\/#organization\",\"name\":\"soundPR\",\"url\":\"https:\/\/www.soundpr.it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.soundpr.it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.soundpr.it\/wp-content\/uploads\/2019\/07\/Logo-hd-wht.png\",\"contentUrl\":\"https:\/\/www.soundpr.it\/wp-content\/uploads\/2019\/07\/Logo-hd-wht.png\",\"width\":168,\"height\":69,\"caption\":\"soundPR\"},\"image\":{\"@id\":\"https:\/\/www.soundpr.it\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"The North Face conferma il suo impegno nella tutela dell\u2019ambiente e della natura portando la sua Community in Valle d\u2019Aosta per un MOUNTAIN EDUCATIONAL TREKKING - soundPR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.soundpr.it\/news\/the-north-face-conferma-il-suo-impegno-nella-tutela-dellambiente-e-della-natura-portando-la-sua-community-in-valle-daosta-per-un-mountain-educational-trekking\/","og_locale":"en_US","og_type":"article","og_title":"The North Face conferma il suo impegno nella tutela dell\u2019ambiente e della natura portando la sua Community in Valle d\u2019Aosta per un MOUNTAIN EDUCATIONAL TREKKING - soundPR","og_description":"Appuntamento il 13 luglio a Gressoney-Saint-Jean Il prossimo appuntamento fuori citt\u00e0 organizzato da The North Face per la Community Never Stop Milano sar\u00e0 sui monti della Valle d\u2019Aosta, a Gressoney-Saint-Jean. Un\u2019occasione per scoprire posti incantevoli immersi della natura e contribuire attivamente a ripulire i sentieri dai rifiuti, riportando cos\u00ec l\u2019ambiente al suo stato naturale. Sabato [...]Read More...","og_url":"https:\/\/www.soundpr.it\/news\/the-north-face-conferma-il-suo-impegno-nella-tutela-dellambiente-e-della-natura-portando-la-sua-community-in-valle-daosta-per-un-mountain-educational-trekking\/","og_site_name":"soundPR","og_image":[{"width":721,"height":345,"url":"https:\/\/www.soundpr.it\/wp-content\/uploads\/2019\/07\/TNF_MOUNTAIN-EDUCATIONAL-TREKKING.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.soundpr.it\/news\/the-north-face-conferma-il-suo-impegno-nella-tutela-dellambiente-e-della-natura-portando-la-sua-community-in-valle-daosta-per-un-mountain-educational-trekking\/","url":"https:\/\/www.soundpr.it\/news\/the-north-face-conferma-il-suo-impegno-nella-tutela-dellambiente-e-della-natura-portando-la-sua-community-in-valle-daosta-per-un-mountain-educational-trekking\/","name":"The North Face conferma il suo impegno nella tutela dell\u2019ambiente e della natura portando la sua Community in Valle d\u2019Aosta per un MOUNTAIN EDUCATIONAL TREKKING - soundPR","isPartOf":{"@id":"https:\/\/www.soundpr.it\/#website"},"datePublished":"2019-07-03T22:00:00+00:00","dateModified":"2019-07-03T22:00:00+00:00","breadcrumb":{"@id":"https:\/\/www.soundpr.it\/news\/the-north-face-conferma-il-suo-impegno-nella-tutela-dellambiente-e-della-natura-portando-la-sua-community-in-valle-daosta-per-un-mountain-educational-trekking\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.soundpr.it\/news\/the-north-face-conferma-il-suo-impegno-nella-tutela-dellambiente-e-della-natura-portando-la-sua-community-in-valle-daosta-per-un-mountain-educational-trekking\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.soundpr.it\/news\/the-north-face-conferma-il-suo-impegno-nella-tutela-dellambiente-e-della-natura-portando-la-sua-community-in-valle-daosta-per-un-mountain-educational-trekking\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.soundpr.it\/"},{"@type":"ListItem","position":2,"name":"The North Face conferma il suo impegno nella tutela dell\u2019ambiente e della natura portando la sua Community in Valle d\u2019Aosta per un MOUNTAIN EDUCATIONAL TREKKING"}]},{"@type":"WebSite","@id":"https:\/\/www.soundpr.it\/#website","url":"https:\/\/www.soundpr.it\/","name":"soundPR","description":"Sound Public Relations","publisher":{"@id":"https:\/\/www.soundpr.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.soundpr.it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.soundpr.it\/#organization","name":"soundPR","url":"https:\/\/www.soundpr.it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.soundpr.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.soundpr.it\/wp-content\/uploads\/2019\/07\/Logo-hd-wht.png","contentUrl":"https:\/\/www.soundpr.it\/wp-content\/uploads\/2019\/07\/Logo-hd-wht.png","width":168,"height":69,"caption":"soundPR"},"image":{"@id":"https:\/\/www.soundpr.it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.soundpr.it\/en\/wp-json\/wp\/v2\/news\/17405"}],"collection":[{"href":"https:\/\/www.soundpr.it\/en\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/www.soundpr.it\/en\/wp-json\/wp\/v2\/types\/news"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.soundpr.it\/en\/wp-json\/wp\/v2\/media\/17406"}],"wp:attachment":[{"href":"https:\/\/www.soundpr.it\/en\/wp-json\/wp\/v2\/media?parent=17405"}],"wp:term":[{"taxonomy":"news_categories","embeddable":true,"href":"https:\/\/www.soundpr.it\/en\/wp-json\/wp\/v2\/news_categories?post=17405"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}