{"id":15178,"date":"2013-05-17T00:00:00","date_gmt":"2013-05-16T22:00:00","guid":{"rendered":"https:\/\/www.soundpr.it\/post_news\/the-north-face-e-travel-configurator-insieme-per-viaggi-avventura-oltre-i-confini-della-vacanza\/"},"modified":"2013-05-17T00:00:00","modified_gmt":"2013-05-16T22:00:00","slug":"the-north-face-e-travel-configurator-insieme-per-viaggi-avventura-oltre-i-confini-della-vacanza","status":"publish","type":"news","link":"https:\/\/www.soundpr.it\/en\/news\/the-north-face-e-travel-configurator-insieme-per-viaggi-avventura-oltre-i-confini-della-vacanza\/","title":{"rendered":"The North Face and Travel Configuration together  for adventure-tours beyond the holiday \u2018s frontiers"},"content":{"rendered":"<p><\/p>\n<p><\/p>","protected":false},"featured_media":15179,"template":"","news_categories":[143],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>The North Face e Travel Configurator insieme per viaggi-avventura oltre i confini della vacanzaThe North Face and Travel Configuration together for adventure-tours beyond the holiday \u2018s frontiers - soundPR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.soundpr.it\/news\/the-north-face-e-travel-configurator-insieme-per-viaggi-avventura-oltre-i-confini-della-vacanza\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The North Face e Travel Configurator insieme per viaggi-avventura oltre i confini della vacanzaThe North Face and Travel Configuration together for adventure-tours beyond the holiday \u2018s frontiers - soundPR\" \/>\n<meta property=\"og:description\" content=\"[...]Read More...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.soundpr.it\/news\/the-north-face-e-travel-configurator-insieme-per-viaggi-avventura-oltre-i-confini-della-vacanza\/\" \/>\n<meta property=\"og:site_name\" content=\"soundPR\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.soundpr.it\/wp-content\/uploads\/2019\/07\/TNF_TravelConfigurator.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"624\" \/>\n\t<meta property=\"og:image:height\" content=\"295\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.soundpr.it\/news\/the-north-face-e-travel-configurator-insieme-per-viaggi-avventura-oltre-i-confini-della-vacanza\/\",\"url\":\"https:\/\/www.soundpr.it\/news\/the-north-face-e-travel-configurator-insieme-per-viaggi-avventura-oltre-i-confini-della-vacanza\/\",\"name\":\"The North Face e Travel Configurator insieme per viaggi-avventura oltre i confini della vacanzaThe North Face and Travel Configuration together for adventure-tours beyond the holiday \u2018s frontiers - soundPR\",\"isPartOf\":{\"@id\":\"https:\/\/www.soundpr.it\/#website\"},\"datePublished\":\"2013-05-16T22:00:00+00:00\",\"dateModified\":\"2013-05-16T22:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.soundpr.it\/news\/the-north-face-e-travel-configurator-insieme-per-viaggi-avventura-oltre-i-confini-della-vacanza\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.soundpr.it\/news\/the-north-face-e-travel-configurator-insieme-per-viaggi-avventura-oltre-i-confini-della-vacanza\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.soundpr.it\/news\/the-north-face-e-travel-configurator-insieme-per-viaggi-avventura-oltre-i-confini-della-vacanza\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.soundpr.it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"The North Face e Travel Configurator insieme per viaggi-avventura oltre i confini della vacanza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.soundpr.it\/#website\",\"url\":\"https:\/\/www.soundpr.it\/\",\"name\":\"soundPR\",\"description\":\"Sound Public Relations\",\"publisher\":{\"@id\":\"https:\/\/www.soundpr.it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.soundpr.it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.soundpr.it\/#organization\",\"name\":\"soundPR\",\"url\":\"https:\/\/www.soundpr.it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.soundpr.it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.soundpr.it\/wp-content\/uploads\/2019\/07\/Logo-hd-wht.png\",\"contentUrl\":\"https:\/\/www.soundpr.it\/wp-content\/uploads\/2019\/07\/Logo-hd-wht.png\",\"width\":168,\"height\":69,\"caption\":\"soundPR\"},\"image\":{\"@id\":\"https:\/\/www.soundpr.it\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"The North Face e Travel Configurator insieme per viaggi-avventura oltre i confini della vacanzaThe North Face and Travel Configuration together for adventure-tours beyond the holiday \u2018s frontiers - soundPR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.soundpr.it\/news\/the-north-face-e-travel-configurator-insieme-per-viaggi-avventura-oltre-i-confini-della-vacanza\/","og_locale":"en_US","og_type":"article","og_title":"The North Face e Travel Configurator insieme per viaggi-avventura oltre i confini della vacanzaThe North Face and Travel Configuration together for adventure-tours beyond the holiday \u2018s frontiers - soundPR","og_description":"[...]Read More...","og_url":"https:\/\/www.soundpr.it\/news\/the-north-face-e-travel-configurator-insieme-per-viaggi-avventura-oltre-i-confini-della-vacanza\/","og_site_name":"soundPR","og_image":[{"width":624,"height":295,"url":"https:\/\/www.soundpr.it\/wp-content\/uploads\/2019\/07\/TNF_TravelConfigurator.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.soundpr.it\/news\/the-north-face-e-travel-configurator-insieme-per-viaggi-avventura-oltre-i-confini-della-vacanza\/","url":"https:\/\/www.soundpr.it\/news\/the-north-face-e-travel-configurator-insieme-per-viaggi-avventura-oltre-i-confini-della-vacanza\/","name":"The North Face e Travel Configurator insieme per viaggi-avventura oltre i confini della vacanzaThe North Face and Travel Configuration together for adventure-tours beyond the holiday \u2018s frontiers - soundPR","isPartOf":{"@id":"https:\/\/www.soundpr.it\/#website"},"datePublished":"2013-05-16T22:00:00+00:00","dateModified":"2013-05-16T22:00:00+00:00","breadcrumb":{"@id":"https:\/\/www.soundpr.it\/news\/the-north-face-e-travel-configurator-insieme-per-viaggi-avventura-oltre-i-confini-della-vacanza\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.soundpr.it\/news\/the-north-face-e-travel-configurator-insieme-per-viaggi-avventura-oltre-i-confini-della-vacanza\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.soundpr.it\/news\/the-north-face-e-travel-configurator-insieme-per-viaggi-avventura-oltre-i-confini-della-vacanza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.soundpr.it\/"},{"@type":"ListItem","position":2,"name":"The North Face e Travel Configurator insieme per viaggi-avventura oltre i confini della vacanza"}]},{"@type":"WebSite","@id":"https:\/\/www.soundpr.it\/#website","url":"https:\/\/www.soundpr.it\/","name":"soundPR","description":"Sound Public Relations","publisher":{"@id":"https:\/\/www.soundpr.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.soundpr.it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.soundpr.it\/#organization","name":"soundPR","url":"https:\/\/www.soundpr.it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.soundpr.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.soundpr.it\/wp-content\/uploads\/2019\/07\/Logo-hd-wht.png","contentUrl":"https:\/\/www.soundpr.it\/wp-content\/uploads\/2019\/07\/Logo-hd-wht.png","width":168,"height":69,"caption":"soundPR"},"image":{"@id":"https:\/\/www.soundpr.it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.soundpr.it\/en\/wp-json\/wp\/v2\/news\/15178"}],"collection":[{"href":"https:\/\/www.soundpr.it\/en\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/www.soundpr.it\/en\/wp-json\/wp\/v2\/types\/news"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.soundpr.it\/en\/wp-json\/wp\/v2\/media\/15179"}],"wp:attachment":[{"href":"https:\/\/www.soundpr.it\/en\/wp-json\/wp\/v2\/media?parent=15178"}],"wp:term":[{"taxonomy":"news_categories","embeddable":true,"href":"https:\/\/www.soundpr.it\/en\/wp-json\/wp\/v2\/news_categories?post=15178"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}